{"id":8829,"date":"2026-03-16T13:51:04","date_gmt":"2026-03-16T18:51:04","guid":{"rendered":"https:\/\/p4s.co\/news\/?p=8829"},"modified":"2026-05-21T14:32:41","modified_gmt":"2026-05-21T19:32:41","slug":"ley-1014-de-emprendimiento-en-colegios","status":"publish","type":"post","link":"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/","title":{"rendered":"Ley 1014 de emprendimiento en colegios"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_56_1 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >&Iacute;ndice de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-6a98b2a228b83\" ><span class=\"\"><span style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-6a98b2a228b83\"  type=\"checkbox\" id=\"item-6a98b2a228b83\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#Guia_maestra_para_aprovechar_la_ley_1014_de_Emprendimiento_en_colegios_mediante_innovacion_tecnologica\" title=\"Gu\u00eda maestra para aprovechar la ley 1014 de Emprendimiento en colegios mediante innovaci\u00f3n tecnol\u00f3gica\">Gu\u00eda maestra para aprovechar la ley 1014 de Emprendimiento en colegios mediante innovaci\u00f3n tecnol\u00f3gica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#Presentacion_de_la_Ley_1014_de_emprendimiento_en_colegios\" title=\"Presentaci\u00f3n de la Ley 1014 de emprendimiento en colegios\">Presentaci\u00f3n de la Ley 1014 de emprendimiento en colegios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#El_espiritu_de_la_ley_1014_de_Emprendimiento_en_colegios\" title=\"El esp\u00edritu de la ley 1014 de Emprendimiento en colegios\">El esp\u00edritu de la ley 1014 de Emprendimiento en colegios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#La_ruta_guiada_y_el_project_manager_para_estudiantes\" title=\"La ruta guiada y el project manager para estudiantes\">La ruta guiada y el project manager para estudiantes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#Buscando_el_equipo_ideal_y_desarrollando_habilidades\" title=\"Buscando el equipo ideal y desarrollando habilidades\">Buscando el equipo ideal y desarrollando habilidades<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#Integrando_a_la_comunidad_mediante_la_ley_1014_de_Emprendimiento_en_colegios\" title=\"Integrando a la comunidad mediante la ley 1014 de Emprendimiento en colegios\">Integrando a la comunidad mediante la ley 1014 de Emprendimiento en colegios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#De_la_simulacion_a_la_competencia_nacional\" title=\"De la simulaci\u00f3n a la competencia nacional\">De la simulaci\u00f3n a la competencia nacional<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#Conexion_viva_con_el_ecosistema_y_contenidos_de_alto_valor\" title=\"Conexi\u00f3n viva con el ecosistema y contenidos de alto valor\">Conexi\u00f3n viva con el ecosistema y contenidos de alto valor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#Control_directivo_y_el_orgullo_estudiantil\" title=\"Control directivo y el orgullo estudiantil\">Control directivo y el orgullo estudiantil<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#Agende_su_consultoria_estrategica_hoy_mismo_y_convierta_su_institucion_en_un_referente_de_innovacion\" title=\"Agende su consultor\u00eda estrat\u00e9gica hoy mismo y convierta su instituci\u00f3n en un referente de innovaci\u00f3n\">Agende su consultor\u00eda estrat\u00e9gica hoy mismo y convierta su instituci\u00f3n en un referente de innovaci\u00f3n<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/p4s.co\/news\/ley-1014-de-emprendimiento-en-colegios\/#Nuestros_asesores_estan_listos_para_guiarlo\" title=\"Nuestros asesores est\u00e1n listos para guiarlo:\">Nuestros asesores est\u00e1n listos para guiarlo:<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Guia_maestra_para_aprovechar_la_ley_1014_de_Emprendimiento_en_colegios_mediante_innovacion_tecnologica\"><\/span>Gu\u00eda maestra para aprovechar la ley 1014 de Emprendimiento en colegios mediante innovaci\u00f3n tecnol\u00f3gica<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>El mundo de hoy avanza a una velocidad vertiginosa impulsado por la tecnolog\u00eda y la innovaci\u00f3n. En este escenario, la educaci\u00f3n tradicional se enfrenta al reto de evolucionar para no quedarse atr\u00e1s. Ya no es suficiente con que los estudiantes memoricen conceptos, es vital que aprendan a crear, iterar y aportar valor real a la sociedad. Es en este punto exacto donde la <strong>ley 1014 de Emprendimiento en colegios<\/strong> deja de ser un simple tr\u00e1mite administrativo y se convierte en el motor de una transformaci\u00f3n profunda. Desde p4s.co hemos dise\u00f1ado un ecosistema digital integral para que las instituciones educativas puedan implementar esta normativa no solo con rigor, sino con herramientas dignas de las mejores aceleradoras de startups del mundo.<\/p>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Presentacion_de_la_Ley_1014_de_emprendimiento_en_colegios\"><\/span>Presentaci\u00f3n de la Ley 1014 de emprendimiento en colegios<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En la siguiente presentaci\u00f3n exploraremos por qu\u00e9 el emprendimiento escolar es la base del futuro profesional de los j\u00f3venes y c\u00f3mo nuestra plataforma soluciona los retos log\u00edsticos, pedag\u00f3gicos y de medici\u00f3n que enfrentan los rectores y coordinadores hoy en d\u00eda.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/drive.google.com\/file\/d\/1za45a3lUurVlydv3P3Gg-_EMiZXrX-e5\/view?usp=sharing\"><strong>Descargar presentaci\u00f3n en PDF.<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/drive.google.com\/file\/d\/1za45a3lUurVlydv3P3Gg-_EMiZXrX-e5\/view?usp=sharing\"><img decoding=\"async\" src=\"https:\/\/cdn-icons-png.flaticon.com\/512\/11180\/11180756.png\" alt=\"\" style=\"width:105px;height:auto\"\/><\/a><\/figure>\n\n\n\n<p><div class=\"youtube-responsive-container\">\n<iframe loading=\"lazy\" src=\"https:\/\/docs.google.com\/presentation\/d\/e\/2PACX-1vRcAUsjl_bKMta3BZA47XJNfDiIDjGPSJEHOGCyF0fkDsJCUBoasycfahSENpRpsrzitoXw17zl-7qE\/pubembed?start=false&#038;loop=false&#038;delayms=3000\" frameborder=\"0\" width=\"960\" height=\"569\" allowfullscreen=\"true\" mozallowfullscreen=\"true\" webkitallowfullscreen=\"true\"><\/iframe>\n<\/div><\/p>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"El_espiritu_de_la_ley_1014_de_Emprendimiento_en_colegios\"><\/span>El esp\u00edritu de la ley 1014 de Emprendimiento en colegios<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"923\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-infografia-1014-partners-for-startups-1024x923.jpg\" alt=\"La ley 1014 busca: Enfoque en Procesos, Soluci\u00f3n de Problemas, Formaci\u00f3n Ciudadana.\" class=\"wp-image-8860\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-infografia-1014-partners-for-startups-1024x923.jpg 1024w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-infografia-1014-partners-for-startups-300x270.jpg 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-infografia-1014-partners-for-startups-768x692.jpg 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-infografia-1014-partners-for-startups-162x146.jpg 162w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-infografia-1014-partners-for-startups-50x45.jpg 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-infografia-1014-partners-for-startups-83x75.jpg 83w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-infografia-1014-partners-for-startups.jpg 1134w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La ley 1014 busca: Enfoque en Procesos, Soluci\u00f3n de Problemas, Formaci\u00f3n Ciudadana.<\/figcaption><\/figure>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<p><\/p>\n\n\n\n<p>Para comprender la magnitud de la oportunidad, debemos remitirnos a la esencia de la legislaci\u00f3n colombiana. El objetivo no es que todos los ni\u00f1os funden empresas de inmediato, sino forjar una <strong>mentalidad creadora<\/strong> y <strong>resiliente.<\/strong> <\/p>\n\n\n\n<p>La normativa es clara en sus mandatos hacia las instituciones educativas:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-medium-font-size\">\u00abEstablecer mecanismos para el desarrollo de la cultura empresarial y el emprendimiento a trav\u00e9s de una red de instrumentos de fomento vinculados al sistema educativo\u00bb<\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u00abPromover el desarrollo de competencias b\u00e1sicas, laborales, ciudadanas y empresariales dentro del sistema educativo formal y no formal.\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Cumplir con la <strong>ley 1014 de Emprendimiento en colegios<\/strong> exige integrar de forma transversal el desarrollo de proyectos y habilidades blandas. Tradicionalmente, esto se ha intentado mediante ferias empresariales espor\u00e1dicas. Sin embargo, en la era de la inteligencia artificial y las startups, estas metodolog\u00edas se quedan cortas. Los estudiantes necesitan conocer los retos de innovaci\u00f3n empresariales reales, entender el mercado y trabajar con metodolog\u00edas \u00e1giles. puedes conocer m\u00e1s de la ley 1014 en <a href=\"https:\/\/www.funcionpublica.gov.co\/eva\/gestornormativo\/norma.php?i=18924\" data-type=\"link\" data-id=\"https:\/\/www.funcionpublica.gov.co\/eva\/gestornormativo\/norma.php?i=18924\" target=\"_blank\" rel=\"noreferrer noopener\">este enlace<\/a>.<\/p>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"254\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-espiritu.webp\" alt=\"\" class=\"wp-image-8869\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-espiritu.webp 900w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-espiritu-300x85.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-espiritu-768x217.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-espiritu-260x73.webp 260w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-espiritu-50x14.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-espiritu-150x42.webp 150w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"La_ruta_guiada_y_el_project_manager_para_estudiantes\"><\/span>La ruta guiada y el project manager para estudiantes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<blockquote class=\"wp-block-quote has-medium-font-size is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Uno de los grandes problemas al ense\u00f1ar innovaci\u00f3n es la falta de estructura.<br>Una idea sin ejecuci\u00f3n es solo una ilusi\u00f3n.<\/p>\n<\/blockquote>\n\n\n\n<p>Por ello, p4s.co cuenta con una ruta de emprendimiento conformada por diferentes fases, que lleva a los j\u00f3venes desde la ideaci\u00f3n inicial hasta la fase de inversi\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-vertical-02-letras-negras-big.png\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"618\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-vertical-02-letras-negras-small.jpg\" alt=\"Infograf\u00eda de la ruta de emprendimiento\" class=\"wp-image-8759\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-vertical-02-letras-negras-small.jpg 800w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-vertical-02-letras-negras-small-300x232.jpg 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-vertical-02-letras-negras-small-768x593.jpg 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-vertical-02-letras-negras-small-189x146.jpg 189w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-vertical-02-letras-negras-small-50x39.jpg 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-vertical-02-letras-negras-small-97x75.jpg 97w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\">Infograf\u00eda de la ruta de emprendimiento<\/figcaption><\/figure>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<p><\/p>\n\n\n\n<p>Para garantizar que esta ruta se cumpla, nuestra plataforma integra un robusto m\u00f3dulo de project manager. Esta herramienta garantiza la ejecuci\u00f3n paso a paso de los proyectos. Cada objetivo de la ruta se desglosa en tareas puntuales montadas en el sistema. Los docentes y estudiantes pueden monitorear el porcentaje de avance, asignar responsables a cada tarea y subir archivos de evidencia que demuestren el cumplimiento. Esto no solo ense\u00f1a gesti\u00f3n de proyectos a nivel profesional, sino que documenta de forma irrefutable el cumplimiento de la norma.<\/p>\n\n\n\n<p>La ruta est\u00e1 dividida en fases. En la siguiente imagen ver\u00e1s las fases que contiene la ruta de emprendimiento en nuestra plataforma:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"592\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-plataforma-fases-1024x592.jpg\" alt=\"Fases de la ruta de emprendimiento en nuestra plataforma\" class=\"wp-image-8757\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-plataforma-fases-1024x592.jpg 1024w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-plataforma-fases-300x173.jpg 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-plataforma-fases-768x444.jpg 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-plataforma-fases-1536x888.jpg 1536w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-plataforma-fases-253x146.jpg 253w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-plataforma-fases-50x29.jpg 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-plataforma-fases-130x75.jpg 130w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-plataforma-fases.jpg 1863w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Fases de la ruta de emprendimiento en nuestra plataforma<\/figcaption><\/figure>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Buscando_el_equipo_ideal_y_desarrollando_habilidades\"><\/span>Buscando el equipo ideal y desarrollando habilidades<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"792\" height=\"446\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-equipo-de-trabajo.webp\" alt=\"Los proyectos exitosos se desarrollan en equipo.\" class=\"wp-image-8865\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-equipo-de-trabajo.webp 792w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-equipo-de-trabajo-300x169.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-equipo-de-trabajo-768x432.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-equipo-de-trabajo-260x146.webp 260w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-equipo-de-trabajo-50x28.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-equipo-de-trabajo-133x75.webp 133w\" sizes=\"auto, (max-width: 792px) 100vw, 792px\" \/><\/figure>\n\n\n\n<p>En el ecosistema tecnol\u00f3gico real, los llaneros solitarios rara vez triunfan. El trabajo en equipo es fundamental. Para fomentar esto, la plataforma incluye un innovador m\u00f3dulo para buscar cofundador. Los estudiantes pueden perfilar sus habilidades y unirse con compa\u00f1eros que complementen sus talentos, armando el mejor equipo posible. As\u00ed, cada tarea del project manager tiene un responsable id\u00f3neo.<\/p>\n\n\n\n<p>Adem\u00e1s, entendemos que los j\u00f3venes necesitan gu\u00eda t\u00e9cnica. Cada tarea propuesta en la ruta est\u00e1 acompa\u00f1ada de contenidos educativos dise\u00f1ados espec\u00edficamente para el desarrollo de su entregable. No los dejamos solos frente a la hoja en blanco, les brindamos el conocimiento necesario en el momento exacto en que lo necesitan.<\/p>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Integrando_a_la_comunidad_mediante_la_ley_1014_de_Emprendimiento_en_colegios\"><\/span>Integrando a la comunidad mediante la ley 1014 de Emprendimiento en colegios<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"212\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-trabajo-en-equipo.webp\" alt=\"\" class=\"wp-image-8763\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-trabajo-en-equipo.webp 800w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-trabajo-en-equipo-300x80.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-trabajo-en-equipo-768x204.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-trabajo-en-equipo-260x69.webp 260w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-trabajo-en-equipo-50x13.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-trabajo-en-equipo-150x40.webp 150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Un colegio innovador aprovecha el talento de toda su comunidad. El rol de los exalumnos y los padres de familia toma un protagonismo estelar gracias a nuestro m\u00f3dulo de mentor\u00edas y asesor\u00edas. Profesionales que ya enfrentan el mercado laboral pueden conectarse a la plataforma para guiar a las \u00abstartups\u00bb escolares, brindar retroalimentaci\u00f3n a sus avances y compartir su experiencia.<\/p>\n\n\n\n<p>Esta interacci\u00f3n enriquece profundamente el proceso formativo, genera un networking valioso desde edades tempranas y crea un fuerte sentido de pertenencia entre los egresados y la instituci\u00f3n, elevando el prestigio del colegio a un nuevo nivel.<\/p>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"De_la_simulacion_a_la_competencia_nacional\"><\/span>De la simulaci\u00f3n a la competencia nacional<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"191\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-ruta-al-exito.webp\" alt=\"Una ruta de emprendimiento te acerca al \u00e9xito\" class=\"wp-image-8762\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-ruta-al-exito.webp 800w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-ruta-al-exito-300x72.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-ruta-al-exito-768x183.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-ruta-al-exito-260x62.webp 260w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-ruta-al-exito-50x12.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-ruta-al-exito-150x36.webp 150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>El esfuerzo de meses debe culminar en un evento que marque la vida de los j\u00f3venes. Cumpliendo con nuestra visi\u00f3n de ir m\u00e1s all\u00e1, facilitamos la realizaci\u00f3n de un demoday interno con simulaci\u00f3n de inversiones, donde los equipos presentan su pitch y la comunidad educativa act\u00faa como inversionistas virtuales.<\/p>\n\n\n\n<p>La experiencia continua m\u00e1s all\u00e1 del colegio. Los mejores proyectos tienen la oportunidad de participar en nuestra competencia final nacional, present\u00e1ndose ante jurados nacionales e internacionales. Esto valida socialmente el esfuerzo de los estudiantes y catapulta el posicionamiento de la instituci\u00f3n como un actor activo del ecosistema de emprendimiento nacional.<\/p>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"346\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-competencia-nacional.webp\" alt=\"Los mejores proyectos competir\u00e1n a nivel nacional\" class=\"wp-image-8870\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-competencia-nacional.webp 800w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-competencia-nacional-300x130.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-competencia-nacional-768x332.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-competencia-nacional-260x112.webp 260w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-competencia-nacional-50x22.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/ley-1014-de-emprendimiento-en-colegios-competencia-nacional-150x65.webp 150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conexion_viva_con_el_ecosistema_y_contenidos_de_alto_valor\"><\/span>Conexi\u00f3n viva con el ecosistema y contenidos de alto valor<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"318\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-production-video-live-streaming-podcast.webp\" alt=\"Conoce a los actores del ecosistema de innovaci\u00f3n y emprendimiento en nuestros canales\" class=\"wp-image-8867\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-production-video-live-streaming-podcast.webp 800w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-production-video-live-streaming-podcast-300x119.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-production-video-live-streaming-podcast-768x305.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-production-video-live-streaming-podcast-260x103.webp 260w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-production-video-live-streaming-podcast-50x20.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-production-video-live-streaming-podcast-150x60.webp 150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Para mantener la llama de la innovaci\u00f3n encendida, el aprendizaje debe ser continuo y actualizado. p4s.co transmite contenidos en vivo todas las semanas con actores del ecosistema nacional e internacional. A trav\u00e9s de programas especializados abordamos temas de innovaci\u00f3n, ventas e inversiones.<\/p>\n\n\n\n<p>Nuestros estudiantes y docentes tienen acceso a entrevistas con los protagonistas de los principales eventos de tecnolog\u00eda del pa\u00eds. De esta manera, garantizamos que el cumplimiento de la <strong>ley 1014 de Emprendimiento en colegios<\/strong> no sea un curr\u00edculo est\u00e1tico, sino una ventana abierta al mundo real y a las tendencias globales.<\/p>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Control_directivo_y_el_orgullo_estudiantil\"><\/span>Control directivo y el orgullo estudiantil<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"364\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-dashborad-panel-de-control-ecosistema-de-emprendimiento-cenefa-1024x364.webp\" alt=\"Administra los eventos, proyectos y retos de tu instituci\u00f3n.\" class=\"wp-image-8872\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-dashborad-panel-de-control-ecosistema-de-emprendimiento-cenefa-1024x364.webp 1024w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-dashborad-panel-de-control-ecosistema-de-emprendimiento-cenefa-300x107.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-dashborad-panel-de-control-ecosistema-de-emprendimiento-cenefa-768x273.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-dashborad-panel-de-control-ecosistema-de-emprendimiento-cenefa-1536x546.webp 1536w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-dashborad-panel-de-control-ecosistema-de-emprendimiento-cenefa-260x92.webp 260w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-dashborad-panel-de-control-ecosistema-de-emprendimiento-cenefa-50x18.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-dashborad-panel-de-control-ecosistema-de-emprendimiento-cenefa-150x53.webp 150w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2026\/03\/p4s.co-dashborad-panel-de-control-ecosistema-de-emprendimiento-cenefa.webp 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Finalmente, el \u00e9xito de cualquier programa escolar depende de la capacidad de la direcci\u00f3n para gestionarlo. Nuestro sistema ofrece un m\u00f3dulo de gesti\u00f3n para rectores y coordinadores que centraliza todas las m\u00e9tricas, facilitando el control sin sobrecargar a los docentes.<\/p>\n\n\n\n<p>Mientras el colegio asegura su excelencia, el alumno construye su portafolio del estudiante. Un perfil digital que compila cada logro, cada reto superado y cada evidencia cargada. Este portafolio se convierte en una validaci\u00f3n social poderosa y una fuente de orgullo estudiantil incalculable, una verdadera carta de presentaci\u00f3n para su futuro universitario y profesional. Implementar la <strong>ley 1014 de Emprendimiento en colegios<\/strong> a trav\u00e9s de p4s.co es, en definitiva, la decisi\u00f3n estrat\u00e9gica que transforma instituciones tradicionales en los semilleros de los l\u00edderes tecnol\u00f3gicos del ma\u00f1ana.<\/p>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Agende_su_consultoria_estrategica_hoy_mismo_y_convierta_su_institucion_en_un_referente_de_innovacion\"><\/span>Agende su consultor\u00eda estrat\u00e9gica hoy mismo y convierta su instituci\u00f3n en un referente de innovaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Aproveche el marco de la Ley 1014 como una oportunidad estrat\u00e9gica para distinguir a su colegio y proyectar a sus estudiantes hacia el \u00e9xito empresarial. <\/p>\n\n\n\n<p>Nuestros asesores especializados est\u00e1n preparados para asesorarlo en la implementaci\u00f3n de un ecosistema que profesionaliza el talento joven, automatiza la gesti\u00f3n docente y vincula su instituci\u00f3n con las redes de emprendimiento m\u00e1s importantes del pa\u00eds. Reserve una consultor\u00eda personalizada para integrar las herramientas de <strong>p4s.co<\/strong> en su modelo formativo y consolidar su prestigio como una instituci\u00f3n pionera en la formaci\u00f3n de fundadores de alto impacto.<\/p>\n\n\n\n<img decoding=\"async\" style=\"width:40px;\" src=\"https:\/\/p4s.co\/photo\/arrow-with-new-letter-icon-gif-animation-2.gif\"\/> \n<a class=\"\" href=\"https:\/\/p4s.co\/colegioSolicitarCita\" rel=\"modal:open\">Solicitar asesor\u00eda gratuita<\/a>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Nuestros_asesores_estan_listos_para_guiarlo\"><\/span>Nuestros asesores est\u00e1n listos para guiarlo:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><td>Asesor<\/td><td>Correo Electr\u00f3nico<\/td><td>Tel\u00e9fono \/ WhatsApp<\/td><\/tr><\/thead><tbody><tr><td><strong>Luis Enrique Sierra<\/strong><\/td><td><a target=\"_blank\" rel=\"noreferrer noopener\" href=\"mailto:les@p4s.co\">les@p4s.co<\/a><\/td><td>315-119-7969<\/td><\/tr><tr><td><strong>Christian Andr\u00e9s Sierra<\/strong><\/td><td><a target=\"_blank\" rel=\"noreferrer noopener\" href=\"mailto:cas@p4s.co\">cas@p4s.co<\/a><\/td><td>319-648-3251<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"187\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-seguir.webp\" alt=\"\" class=\"wp-image-8766\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-seguir.webp 800w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-seguir-300x70.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-seguir-768x180.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-seguir-260x61.webp 260w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-seguir-50x12.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2025\/11\/ruta-de-emprendimiento-seguir-150x35.webp 150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><\/p>\n<\/blockquote>\n\n\n<p><!--EndFragment--><\/p>\n<p><!--EndFragment--><\/p>","protected":false},"excerpt":{"rendered":"<p>Descubre la gu\u00eda definitiva para implementar la ley 1014 de Emprendimiento en colegios con tecnolog\u00eda. Con la plataforma de p4s.co, los estudiantes viven la experiencia real de crear startups mediante project managers, m\u00f3dulos de cofundadores, mentor\u00edas y un emocionante demoday. Transforma tu colegio hoy.<\/p>\n","protected":false},"author":7,"featured_media":8850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,31],"tags":[339],"class_list":["post-8829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-edutech","tag-ley-de-emprendimiento"],"_links":{"self":[{"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/posts\/8829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/comments?post=8829"}],"version-history":[{"count":22,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/posts\/8829\/revisions"}],"predecessor-version":[{"id":9144,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/posts\/8829\/revisions\/9144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/media\/8850"}],"wp:attachment":[{"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/media?parent=8829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/categories?post=8829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/tags?post=8829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}