{"id":4846,"date":"2026-02-18T16:01:00","date_gmt":"2026-02-18T21:01:00","guid":{"rendered":"https:\/\/p4s.co\/news\/?p=4846"},"modified":"2026-06-03T23:07:04","modified_gmt":"2026-06-04T04:07:04","slug":"postular-charlas-en-los-eventos-de-comunidad","status":"publish","type":"post","link":"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/","title":{"rendered":"Postular charlas en los eventos de comunidad es f\u00e1cil"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_56_1 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >&Iacute;ndice de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\" role=\"button\"><label for=\"item-6a57cae7d851f\" ><span class=\"\"><span style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input aria-label=\"Toggle\" aria-label=\"item-6a57cae7d851f\"  type=\"checkbox\" id=\"item-6a57cae7d851f\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Buscamos_nuevos_talentos\" title=\"Buscamos nuevos talentos\">Buscamos nuevos talentos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Conviertete_en_Speaker_al_postular_charlas_en_los_eventos_de_comunidad\" title=\"Convi\u00e9rtete en Speaker al postular charlas en los eventos de comunidad\">Convi\u00e9rtete en Speaker al postular charlas en los eventos de comunidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Por_que_postular_charlas_en_los_eventos_de_comunidad\" title=\"Por qu\u00e9 postular charlas en los eventos de comunidad\">Por qu\u00e9 postular charlas en los eventos de comunidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Cual_es_el_proceso_para_postular_charlas_en_los_eventos_de_comunidad\" title=\"Cu\u00e1l es el proceso para postular charlas en los eventos de comunidad\">Cu\u00e1l es el proceso para postular charlas en los eventos de comunidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#%C2%BFComo_puedes_postular_charlas_en_los_eventos_de_comunidad\" title=\"\u00bfC\u00f3mo puedes postular charlas en los eventos de comunidad?\">\u00bfC\u00f3mo puedes postular charlas en los eventos de comunidad?<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Video_detallado_para_postular_charlas\" title=\"Video detallado para postular charlas\">Video detallado para postular charlas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Registrar_charlas_en_los_eventos_de_comunidad\" title=\"Registrar charlas en los eventos de comunidad\">Registrar charlas en los eventos de comunidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Siguientes_pasos_en_la_edicion_de_la_charla\" title=\"Siguientes pasos en la edici\u00f3n de la charla\">Siguientes pasos en la edici\u00f3n de la charla<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Datos_basicos\" title=\"Datos b\u00e1sicos\">Datos b\u00e1sicos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Descripcion_de_la_charla\" title=\"Descripci\u00f3n de la charla\">Descripci\u00f3n de la charla<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Condiciones_de_tu_charla\" title=\"Condiciones de tu charla\">Condiciones de tu charla<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Multimedios\" title=\"Multimedios\">Multimedios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Diapositivas\" title=\"Diapositivas\">Diapositivas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Como_montar_la_presentacion_de_tu_charla_en_nuestra_plataforma\" title=\"C\u00f3mo montar la presentaci\u00f3n de tu charla en nuestra plataforma.\">C\u00f3mo montar la presentaci\u00f3n de tu charla en nuestra plataforma.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Publicar_la_presentacion_en_la_Web\" title=\"Publicar la presentaci\u00f3n en la Web\">Publicar la presentaci\u00f3n en la Web<\/a><ul class='ez-toc-list-level-4'><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4'><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Videos\" title=\"Videos\">Videos<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Ejemplo_de_postulacion_de_una_charla_con_diapositivas_y_video\" title=\"Ejemplo de postulaci\u00f3n de una charla con diapositivas y video\">Ejemplo de postulaci\u00f3n de una charla con diapositivas y video<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Ayuda_a_la_mano_al_momento_de_subir_la_diapositiva_para_postular_la_charla\" title=\"Ayuda a la mano al momento de subir la diapositiva para postular la charla.\">Ayuda a la mano al momento de subir la diapositiva para postular la charla.<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Banner_de_charla\" title=\"Banner de charla \">Banner de charla <\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Short_URL\" title=\"Short URL\">Short URL<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Categorias\" title=\"Categor\u00edas\">Categor\u00edas<\/a><ul class='ez-toc-list-level-4'><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Vincular_una_categoria_a_la_charla\" title=\"Vincular una categor\u00eda a la charla\">Vincular una categor\u00eda a la charla<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Creacion_de_una_nueva_categoria_al_postular_charlas_en_los_eventos_de_comunidad\" title=\"Creaci\u00f3n de una nueva categor\u00eda al postular charlas en los eventos de comunidad\">Creaci\u00f3n de una nueva categor\u00eda al postular charlas en los eventos de comunidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Vista_de_las_categorias_en_la_landing_page_de_la_charla\" title=\"Vista de las categor\u00edas en la landing page de la charla\">Vista de las categor\u00edas en la landing page de la charla<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Eventos_al_postular_charlas_en_los_eventos_de_comunidad\" title=\"Eventos al postular charlas en los eventos de comunidad\">Eventos al postular charlas en los eventos de comunidad<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Vincular_la_charla_a_un_evento\" title=\"Vincular la charla a un evento\">Vincular la charla a un evento<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Lista_de_eventos_de_la_charla\" title=\"Lista de eventos de la charla\">Lista de eventos de la charla<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Desvincular_la_charla_a_un_evento\" title=\"Desvincular la charla a un evento\">Desvincular la charla a un evento<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Una_charla_postulada_en_varios_eventos_de_comunidad\" title=\"Una charla postulada en varios eventos de comunidad\">Una charla postulada en varios eventos de comunidad<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Obtener_la_Landing_Page_de_la_charla\" title=\"Obtener la Landing Page de la charla\">Obtener la Landing Page de la charla<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Compartir_tu_charla_para_recibir_votos\" title=\"Compartir tu charla para recibir votos\">Compartir tu charla para recibir votos<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-32\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Facebook_Debugger_al_postular_charlas_en_los_eventos_de_comunidad\" title=\"Facebook Debugger al postular charlas en los eventos de comunidad\">Facebook Debugger al postular charlas en los eventos de comunidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-33\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Twitter_Card_para_postular_charlas_en_los_eventos_de_comunidad\" title=\"Twitter Card para postular charlas en los eventos de comunidad\">Twitter Card para postular charlas en los eventos de comunidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-34\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#LinkedIn\" title=\"LinkedIn\">LinkedIn<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-35\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#WhatsApp\" title=\"WhatsApp\">WhatsApp<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-36\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Compartir_desde_la_Landing_Page_de_las_charlas_en_los_eventos_de_comunidad\" title=\"Compartir desde la Landing Page de las charlas en los eventos de comunidad\">Compartir desde la Landing Page de las charlas en los eventos de comunidad<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-37\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Votaciones_al_postular_charlas_en_los_eventos_de_comunidad\" title=\"Votaciones al postular charlas en los eventos de comunidad\">Votaciones al postular charlas en los eventos de comunidad<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-38\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Votar_en_la_Landing_Page_de_una_charla\" title=\"Votar en la Landing Page de una charla\">Votar en la Landing Page de una charla<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-39\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Votar_por_charlas_en_los_eventos_de_comunidad\" title=\"Votar por charlas en los eventos de comunidad\">Votar por charlas en los eventos de comunidad<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-40\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Pedir_votos_al_publico_externo_a_p4sco\" title=\"Pedir votos al p\u00fablico externo a p4s.co\">Pedir votos al p\u00fablico externo a p4s.co<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-41\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#E-mail_de_confirmacion_al_votar_por_charlas_en_eventos_de_comunidad\" title=\"E-mail de confirmaci\u00f3n al votar por charlas en eventos de comunidad\">E-mail de confirmaci\u00f3n al votar por charlas en eventos de comunidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-42\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Voto_confirmado\" title=\"Voto confirmado\">Voto confirmado<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-43\" href=\"https:\/\/p4s.co\/news\/postular-charlas-en-los-eventos-de-comunidad\/#Contenidos_todas_las_semanas\" title=\"Contenidos todas las semanas\">Contenidos todas las semanas<\/a><\/li><\/ul><\/nav><\/div>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Buscamos_nuevos_talentos\"><\/span>Buscamos nuevos talentos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En los \u00faltimo a\u00f1os nuestra comunidad ha logrado mayor alcance geogr\u00e1fico debido a la virtualizaci\u00f3n de nuestros eventos, esta situaci\u00f3n nos presenta dos grandes retos: el primero, mejorar los temas y los contenidos ofrecidos y el segundo reto consiste en satisfacer las necesidades de las personas que quieren ser <em>conferencistas<\/em>, brind\u00e1ndoles un espacio para la formaci\u00f3n de nuevos talentos, donde los interesados puedan postular charlas en los eventos de comunidad y al mismo tiempo logren desarrollar las habilidades suficientes para dictar una conferencia y construir una audiencia.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>El conocimiento de la humanidad se fortalece en comunidad.<\/p>\n<cite>Edward Ramirez Avella<\/cite><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conviertete_en_Speaker_al_postular_charlas_en_los_eventos_de_comunidad\"><\/span>Convi\u00e9rtete en Speaker al postular charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Vivimos en un mundo sumamente competitivo, d\u00f3nde el conocimiento t\u00e9cnico ya no se sustenta \u00fanicamente con t\u00edtulos acad\u00e9micos, sino con habilidades blandas como el aprendizaje constante, la adaptaci\u00f3n y la capacidad de transmitir ideas de forma clara, tanto personalmente como en un auditorio abierto al p\u00fablico.<\/p>\n\n\n\n<p>Por esta raz\u00f3n dise\u00f1amos este nuevo servicio en el que podr\u00e1s postular charlas en los eventos de comunidad, por ejemplo el <a href=\"https:\/\/p4s.co\/news\/p4s-fest\/\">p4s Fest<\/a>, de manera que logres presentarte ante auditorios y de igual forma a trav\u00e9s de Live Videostreaming en nuestros canales de <a href=\"https:\/\/www.youtube.com\/p4slive\">YouTube<\/a>, <a href=\"https:\/\/www.facebook.com\/p4sco\/videos\/\">Facebook<\/a> y <a href=\"https:\/\/www.linkedin.com\/company\/p4sco\/videos\/\">LinkedIn<\/a>; claro est\u00e1, tenemos un proceso de selecci\u00f3n basado en votaciones que veremos m\u00e1s adelante.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/speaker-banner-tiny.webp\" alt=\"microfono\" class=\"wp-image-4991\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Por_que_postular_charlas_en_los_eventos_de_comunidad\"><\/span>Por qu\u00e9 postular charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es posible que ya tengas experiencia creando contenidos o incluso present\u00e1ndolos; por consiguiente te puedes estar preguntando \u00bfpor qu\u00e9 participar?<\/p>\n\n\n\n<p>Estamos buscando personas que deseen: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mejorar su <a href=\"https:\/\/p4s.co\/news\/construir-tu-marca-personal-como-emprendedor\/\">marca personal<\/a> a trav\u00e9s de la participaci\u00f3n en eventos de comunidad.<\/li>\n\n\n\n<li>Aumentar su red de contactos, as\u00ed como las oportunidades de negocio.<\/li>\n\n\n\n<li>Renovar su imagen en Social Media adem\u00e1s de ganar m\u00e1s seguidores.<\/li>\n\n\n\n<li>Adquirir habilidades para hablar en p\u00fablico de forma eficiente y al mismo tiempo cautivar a los espectadores.<\/li>\n\n\n\n<li>Ser reconocidos como expertos en las tem\u00e1ticas presentadas en los eventos.<\/li>\n\n\n\n<li>Finalmente ofrecer sus productos o servicios a grandes audiencias.<\/li>\n<\/ul>\n\n\n\n<p>Realizar conferencias es una oportunidad maravillosa para conocer personas interesantes, hacer negocios, viajar e incluso convertirlo en un modelo de ingresos recurrentes.<\/p>\n\n\n\n<p>Si quieres motivarte, te invitamos a conocer nuestra nueva <a href=\"https:\/\/p4s.co\/news\/comunidad-de-ciberseguridad\/\">comunidad de ciberseguridad<\/a>, donde adem\u00e1s de aprender, podr\u00e1s estar en contacto con m\u00e1s entusiastas como t\u00fa.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/bolitas.webp\" alt=\"proceso\" class=\"wp-image-4997\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cual_es_el_proceso_para_postular_charlas_en_los_eventos_de_comunidad\"><\/span>Cu\u00e1l es el proceso para postular charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Registrarse en el evento donde quieres ofrecer la charla.<\/li>\n\n\n\n<li>Registrar una charla en nuestro sistema. (Encontrar\u00e1s el proceso m\u00e1s adelante).<\/li>\n\n\n\n<li>Vincular la charla al evento donde quieres participar.<\/li>\n\n\n\n<li>Nuestro sistema te generar\u00e1 una Landing Page con la que podr\u00e1s conseguir votos para tu charla. Ac\u00e1 puedes ver un ejemplo de p\u00e1gina de una charla: <a href=\"https:\/\/p4s.co\/corporate-venturing\">Corporate Venturing<\/a><\/li>\n\n\n\n<li>Presentaremos a las charlas m\u00e1s votadas en el evento de comunidad.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_puedes_postular_charlas_en_los_eventos_de_comunidad\"><\/span>\u00bfC\u00f3mo puedes postular charlas en los eventos de comunidad?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A continuaci\u00f3n ver\u00e1s el procedimiento para que registres tus charlas en nuestra plataforma; puedes verlo en video de manera detallada o tambi\u00e9n lo puedes ver paso a paso en texto y con capturas de pantalla.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Video_detallado_para_postular_charlas\"><\/span>Video detallado para postular charlas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Te presentamos un video con toda la informaci\u00f3n acerca de c\u00f3mo puedes postular charlas en los eventos de comunidad; este es el medio recomendado para que aprendas a postular charlas, porque en \u00e9l encontrar\u00e1s c\u00f3mo generar una portada, generar una presentaci\u00f3n con slides y c\u00f3mo usarla en la Landing Page para recibir votos de los interesados.<\/p>\n\n\n\n<p><div class=\"youtube-responsive-container\">\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/TSC5w5nG8Jg\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe>\n<\/div><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Registrar_charlas_en_los_eventos_de_comunidad\"><\/span>Registrar charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Para postular charlas en los eventos de comunidad, primero debes registrarla en la plataforma, para esto debes estar <a href=\"https:\/\/p4s.co\/login\">logueado<\/a> (si no tienes una cuenta <a href=\"https:\/\/p4s.co\/registro\">ac\u00e1 la puedes crear<\/a>) despu\u00e9s ir al men\u00fa <em>Eventos<\/em> y seleccionar la opci\u00f3n <em>Mis Charlas<\/em>:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/01-menu-eventos-registro-charla.webp\" alt=\"postular charlas en los eventos de comunidad en el men\u00fa eventos\" class=\"wp-image-4996\" style=\"width:515px;height:375px\"\/><figcaption class=\"wp-element-caption\">Postular charlas en los eventos de comunidad en el men\u00fa eventos.<\/figcaption><\/figure><\/div>\n\n\n<p>Esa opci\u00f3n del men\u00fa te llevar\u00e1 al listado de charlas, en caso que tengas charlas ya registradas podr\u00e1s consultarlas o editarlas seg\u00fan necesites; ahora bien, si deseas registrar una nueva charla debes usar el bot\u00f3n \u00abCrear nueva charla\u00bb que encontrar\u00e1s en la parte superior de la pantalla:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/10-boton-nueva-charla-eventos-registro-charla.webp\" alt=\"Bot\u00f3n crear nueva charla para postular charlas en los eventos de comunidad\" class=\"wp-image-4999\" style=\"width:375px;height:224px\"\/><figcaption class=\"wp-element-caption\">Bot\u00f3n para crear nueva charla<\/figcaption><\/figure><\/div>\n\n\n<p>Al comienzo el sistema s\u00f3lo te pedir\u00e1 tres datos acerca de tu charla de comunidad:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/20-form-registro-charla.webp\" alt=\"primer formulario para postular charlas\" class=\"wp-image-5003\" style=\"width:446px;height:324px\"\/><figcaption class=\"wp-element-caption\">S\u00f3lo hay dos datos necesarios para empezar a registrar una charla de comunidad.<\/figcaption><\/figure><\/div>\n\n\n<p>Como podr\u00e1s ves, existe la posibilidad que digites una URL que complemente el tema que est\u00e1s postulando al momento de registrar tu charla, sin embargo es completamente opcional, de igual forma puedes registrar un slogan que sea llamativo, debido a que este ser\u00e1 el texto que se mostrar\u00e1 en la Landing Page de la nueva charla y en sus respectivas publicaciones en redes social como tambi\u00e9n en los chats como Telegram, WhatsApp, Slack, Discord, etc. Es por ello que debes elegir una muy buena frase en este punto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Siguientes_pasos_en_la_edicion_de_la_charla\"><\/span>Siguientes pasos en la edici\u00f3n de la charla<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Siguiendo con el registro para postular charlas en los eventos de comunidad, el sistema te ofrece los siguientes pasos:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/30-pasos-edicion-charla.webp\" alt=\"Pasos al postular charlas en los eventos de comunidad\" class=\"wp-image-5006\"\/><figcaption class=\"wp-element-caption\">Pasos al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Datos_basicos\"><\/span>Datos b\u00e1sicos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>De esta forma se puede editar el nombre de la charla y la URL, claro est\u00e1 que esta \u00faltima es opcional; por lo tanto podr\u00e1s cambiar estos datos cuantas veces consideres necesario.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"636\" height=\"334\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/imagen.png\" alt=\"Datos b\u00e1sicos al postular charlas en los eventos de comunidad\" class=\"wp-image-5007\" style=\"width:406px;height:213px\"\/><figcaption class=\"wp-element-caption\">Datos b\u00e1sicos al postular charlas en los eventos de comunidad<\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Descripcion_de_la_charla\"><\/span>Descripci\u00f3n de la charla<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Puede que el <em>slogan<\/em> sea bastante llamativo, sin embargo debemos generar un inter\u00e9s genuino en los miembros de la comunidad y el p\u00fablico en general, para que consulten nuestra charla y sobre todo para lograr que voten a favor de nuestra postulaci\u00f3n. Si hacemos un buen trabajo en este punto, seguramente conseguiremos que el p\u00fablico tambi\u00e9n la recomiende y como resultado obtengamos m\u00e1s votos a favor.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/01\/40-descripcion-edicion-charla.webp\" alt=\"Descripci\u00f3n al postular charlas en los eventos de comunidad\" class=\"wp-image-5011\" style=\"width:567px;height:380px\"\/><figcaption class=\"wp-element-caption\">Descripci\u00f3n al postular charlas en los eventos de comunidad.<\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Condiciones_de_tu_charla\"><\/span>Condiciones de tu charla<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Despu\u00e9s de haber registrado la descripci\u00f3n, es importante que des a conocer las condiciones que tienes para ofrecer tu charla, a pesar que este punto es opcional, en este punto puedes empezar a mostrar tu car\u00e1cter como conferencista estableciendo l\u00edmites o realizando sugerencias a los espectadores de tu contenido, en consecuencia lograr\u00e1s conectar de mejor manera con tu audiencia generando un inter\u00e9s natural a tus ideas y propuestas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/50-condiciones-edicion-charla.webp\" alt=\"Condiciones al postular charlas en los eventos de comunidad.\" class=\"wp-image-5013\"\/><figcaption class=\"wp-element-caption\">Condiciones al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Multimedios\"><\/span>Multimedios<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para presentar mejor tu charla ante los interesados y posibles votantes, es importante contar con un <strong>video<\/strong> y\/o una <strong>presentaci\u00f3n<\/strong> con algunos <strong>slides<\/strong> donde expliques de qu\u00e9 se trata tu charla, dando a conocer al p\u00fablico lo que ver\u00e1n en tu exposici\u00f3n si logras el objetivo de estar entre los conferencistas elegidos del evento.<\/p>\n\n\n\n<p>En nuestra plataforma puedes vincular videos de <strong>YouTube<\/strong> y presentaciones de <strong>Google Slides y Canva<\/strong> directamente.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Diapositivas\"><\/span>Diapositivas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para postular charlas en los eventos de comunidad debemos contar con una presentaci\u00f3n realizada en Google Slides o Canva preferiblemente. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"178\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/google-o-canva.jpg\" alt=\"\" class=\"wp-image-8986\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/google-o-canva.jpg 320w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/google-o-canva-300x167.jpg 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/google-o-canva-260x146.jpg 260w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/google-o-canva-50x28.jpg 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/google-o-canva-135x75.jpg 135w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/figure><\/div>\n\n\n<p>Te recomendamos hacer tu postulaci\u00f3n haciendo uso de esta plantilla:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-medium-font-size\">Esta plantilla s\u00f3lo es una recomendaci\u00f3n, cada l\u00edder de un proyecto est\u00e1 en la libertad de usarla o agregar objetos que considere conveniente para sus prop\u00f3sitos.<\/p>\n<\/blockquote>\n\n\n\n<p><div class=\"youtube-responsive-container\">\n<iframe loading=\"lazy\" src=\"https:\/\/docs.google.com\/presentation\/d\/e\/2PACX-1vR1oML1JjEoHMmEfsH1vrMvOSz5aQ1phyxdAb_RCYd_02_ceULn65hbwNumg_YkfKrvOUhh1gPfOV3J\/pubembed?start=false&#038;loop=false&#038;delayms=3000\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe>\n<\/div><\/p>\n\n\n\n<p>Ac\u00e1 puedes hacer tu copia de la <a href=\"https:\/\/docs.google.com\/presentation\/d\/1-pPuKjCsY4ZEDz9dV9crhqc_mfIi_1P1aMVLAwAK_ZI\/edit?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">plantilla de postulaci\u00f3n de charlas.<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/cdn-icons-png.freepik.com\/256\/6210\/6210938.png\" alt=\"\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_montar_la_presentacion_de_tu_charla_en_nuestra_plataforma\"><\/span>C\u00f3mo montar la presentaci\u00f3n de tu charla en nuestra plataforma.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En este video ver\u00e1s c\u00f3mo hacer el proceso paso a paso:<\/p>\n\n\n\n<p><div class=\"youtube-responsive-container\">\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/CJQg0nxm9fM\" title=\"YouTube video player\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe>\n<\/div><\/p>\n\n\n\n<p>Recuerda sacar copia de la plantilla para que la puedas editar a tu gusto. Una vez hayas editado la plantilla, debes <strong>\u00abPublicar en la WEB\u00bb<\/strong> tu presentaci\u00f3n. <\/p>\n\n\n\n<p>Ac\u00e1 te dejo una presentaci\u00f3n con instrucciones detalladas acerca de c\u00f3mo publicar tu presentaci\u00f3n en la Web, usando Google Slides:<\/p>\n\n\n\n<p><div class=\"youtube-responsive-container\">\n<iframe loading=\"lazy\" src=\"https:\/\/docs.google.com\/presentation\/d\/e\/2PACX-1vQV1BLSAUY7ZEogLAg2BvXpg89L3yQnNggLusRlJ7lne_HZPuP38pVq_iZa-TwLFJ3hV-Fob4-_LV6v\/embed?start=false&amp;loop=false&amp;delayms=3000\" frameborder=\"0\" width=\"960\" height=\"569\" allowfullscreen=\"true\" mozallowfullscreen=\"true\" webkitallowfullscreen=\"true\"><\/iframe>\n<\/div><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/encrypted-tbn0.gstatic.com\/images?q=tbn:ANd9GcS5A_IAqtHTfUInwbrYIgHfOiS_TeVYMLoCtw&amp;s\" alt=\"\" style=\"width:119px;height:auto\"\/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Publicar_la_presentacion_en_la_Web\"><\/span>Publicar la presentaci\u00f3n en la Web<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para <strong>\u00abPublicar en la Web\u00bb<\/strong> tu presentaci\u00f3n, debes ir al men\u00fa Archivo, seleccionar el submen\u00fa <strong>\u00abCompartir<\/strong> y seleccionar la opci\u00f3n <strong>\u00abPublicar en la Web\u00bb<\/strong>. <\/p>\n\n\n\n<p>Tan pronto hayas publicado en la Web tu presentaci\u00f3n, ver\u00e1s dos (2) opciones: 1. Enlace y <strong>2. Insertar<\/strong> (embed en ingl\u00e9s). <\/p>\n\n\n\n<p>Deber\u00e1s escoger la opci\u00f3n <strong>2. Insertar<\/strong> y copiar el texto del <strong>iFrame<\/strong>. Este texto empieza con <strong>&lt;iframe src. . . <\/strong><\/p>\n\n\n\n<p>Copia todo el texto del <strong>iFrame<\/strong> y p\u00e9galo en la plataforma p4s.co de la siguiente manera:<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"679\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-iFrame.webp\" alt=\"Presentaci\u00f3n con slides al postular charlas en los eventos de comunidad\" class=\"wp-image-9030\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-iFrame.webp 921w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-iFrame-300x221.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-iFrame-768x566.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-iFrame-198x146.webp 198w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-iFrame-50x37.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-iFrame-102x75.webp 102w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><figcaption class=\"wp-element-caption\">Presentaci\u00f3n con slides al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<p>Al lado derecho del campo <strong>iFrame<\/strong> podr\u00e1s ver inmediatamente el bot\u00f3n morado <strong>Probar presentaci\u00f3n<\/strong> con el que podr\u00e1s comprobar si el <strong>iFrame<\/strong> est\u00e1 bien copiado. <\/p>\n\n\n\n<p>En la parte inferior hay un caj\u00f3n en el que podr\u00e1s ver la <strong>\u201cVista previa\u201d<\/strong> de tus diapositivas as\u00ed:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"679\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-vista-previa.webp\" alt=\"Vista previa de la presentaci\u00f3n con slides al postular charlas en los eventos de comunidad\" class=\"wp-image-9031\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-vista-previa.webp 921w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-vista-previa-300x221.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-vista-previa-768x566.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-vista-previa-198x146.webp 198w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-vista-previa-50x37.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-vista-previa-102x75.webp 102w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><figcaption class=\"wp-element-caption\">Vista previa de la presentaci\u00f3n al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<p><strong>NOTA: <\/strong>Si no ves correctamente tu presentaci\u00f3n, verifica que el <strong>iFrame<\/strong> haya quedado bien copiado.<\/p>\n\n\n\n<p>Puedes usar este <strong>iFrame<\/strong> de ejemplo para probar y verificar el formato de la presentaci\u00f3n.<\/p>\n\n\n<div class=\"wp-block-syntaxhighlighter-code \"><pre class=\"brush: xml; title: ; notranslate\" title=\"\">\n&lt;iframe src=&quot;https:\/\/docs.google.com\/presentation\/d\/e\/2PACX-1vR1oML1JjEoHMmEfsH1vrMvOSz5aQ1phyxdAb_RCYd_02_ceULn65hbwNumg_YkfKrvOUhh1gPfOV3J\/pubembed?start=false&amp;loop=false&amp;delayms=3000&quot; frameborder=&quot;0&quot; width=&quot;960&quot; height=&quot;569&quot; allowfullscreen=&quot;true&quot; mozallowfullscreen=&quot;true&quot; webkitallowfullscreen=&quot;true&quot;&gt;&lt;\/iframe&gt;\n<\/pre><\/div>\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Videos\"><\/span>Videos<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>De manera similar a la anterior, para montar un video necesitaremos la <strong>URL<\/strong> del video cargado en <strong>YouTube<\/strong>, para nuestro ejemplo usar\u00e9 este video <a href=\"https:\/\/www.youtube.com\/watch?v=lLntuf3coPU\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.youtube.com\/watch?v=lLntuf3coPU<\/a> de la siguiente manera:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"679\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-youtube-vista-previa.webp\" alt=\"Video en YouTube al postular charlas en los eventos de comunidad\" class=\"wp-image-9045\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-youtube-vista-previa.webp 921w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-youtube-vista-previa-300x221.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-youtube-vista-previa-768x566.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-youtube-vista-previa-198x146.webp 198w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-youtube-vista-previa-50x37.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-youtube-vista-previa-102x75.webp 102w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><figcaption class=\"wp-element-caption\">Video en YouTube al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<p>Igualmente que en el campo de presentaci\u00f3n, al lado derecho podr\u00e1s ver el bot\u00f3n azul <strong>Probar YouTube URL<\/strong>, con el que podr\u00e1s comprobar si la <strong>URL<\/strong> est\u00e1 bien copiada; en la parte inferior hay un caj\u00f3n en el que podr\u00e1s ver la <strong>\u201cVista previa\u201d<\/strong> de tu video as\u00ed.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ejemplo_de_postulacion_de_una_charla_con_diapositivas_y_video\"><\/span>Ejemplo de postulaci\u00f3n de una charla con diapositivas y video<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Te dejo el link a la postulaci\u00f3n que hice de ejemplo: <a href=\"https:\/\/p4s.co\/el-riesgo-de-las-energias-limpias\">https:\/\/p4s.co\/el-riesgo-de-las-energias-limpias<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ayuda_a_la_mano_al_momento_de_subir_la_diapositiva_para_postular_la_charla\"><\/span>Ayuda a la mano al momento de subir la diapositiva para postular la charla.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En todo momento tendr\u00e1s a la mano los links a este documento y tambi\u00e9n al link de la <a href=\"https:\/\/docs.google.com\/presentation\/d\/1-pPuKjCsY4ZEDz9dV9crhqc_mfIi_1P1aMVLAwAK_ZI\/edit?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\">plantilla<\/a>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"679\" src=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-ayuda.webp\" alt=\"\" class=\"wp-image-9046\" srcset=\"https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-ayuda.webp 921w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-ayuda-300x221.webp 300w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-ayuda-768x566.webp 768w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-ayuda-198x146.webp 198w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-ayuda-50x37.webp 50w, https:\/\/p4s.co\/news\/wp-content\/uploads\/2023\/02\/CHARLA-poner-diapositivas-ayuda-102x75.webp 102w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><figcaption class=\"wp-element-caption\">Vista previa del video en YouTube al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Banner_de_charla\"><\/span>Banner de charla <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Un banner es una de las mejores herramientas que tienes para llamar la atenci\u00f3n, por lo tanto te recomendamos que le dediques tiempo a la creaci\u00f3n de este elemento, debido a que ser\u00e1 visible al compartirlo<mark class=\"annotation-text annotation-text-yoast\" id=\"annotation-text-9f11a444-c2ad-4e2b-8262-458eb44d7e22\"><\/mark> a trav\u00e9s de medios electr\u00f3nicos. Para subir el banner de tu charla, te recomendamos usar una imagen con un tama\u00f1o de 820 x 460 en formato PNG o JPG (por el momento no aceptamos im\u00e1genes muy grandes por lo que te pedimos que pongas tu banner en esa dimensi\u00f3n).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/01\/100-banner-edicion-charla.webp\" alt=\"Banner llamativo al postular charlas en los eventos de comunidad\" class=\"wp-image-5021\"\/><figcaption class=\"wp-element-caption\">Banner llamativo al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Short_URL\"><\/span>Short URL<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>La URL corta es la parte de la URL que resume el nombre de tu charla, tambi\u00e9n es conocida como <em>Slug,<\/em> sirve para poder compartir la Landing Page de la charla a trav\u00e9s de medios digitales; adem\u00e1s de servir como referencia al interior de nuestra plataforma, la URL corta sirve para mejorar el SEO de la charla debido a que es la parte le\u00edda en los motores de b\u00fasqueda, para ello ofrecemos un campo de la siguiente forma:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/110-slug-edicion-charla.webp\" alt=\"URL corta o slug al postular charlas en los eventos de comunidad\" class=\"wp-image-5022\"\/><figcaption class=\"wp-element-caption\">URL corta o slug al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<p>Asimismo cuando cambias la URL corta, el sistema te ofrece un link para que lo pruebes de inmediato y as\u00ed ver como va quedando tu Landing Page  de charla al interior de nuestra plataforma, por ejemplo: https:\/\/p4s.co\/mi-charla<\/p>\n\n\n\n<p>Puedes consulta la Landing Page de esta charla de ejemplo en esa misma URL: <a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/p4s.co\/el-riesgo-de-las-energias-limpias\" target=\"_blank\">https:\/\/p4s.co\/el-riesgo-de-las-energias-limpias<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Categorias\"><\/span>Categor\u00edas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Para mejorar la clasificaci\u00f3n de las <strong>charlas<\/strong> en los eventos de comunidad y permitir un mejor posicionamiento y b\u00fasqueda de posibles interesados, hemos dispuesto una lista de categor\u00edas que se podr\u00e1n usar como etiquetas. A continuaci\u00f3n te explico como agregar categor\u00edas:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/120-CATEGORIAS-edicion-charla.webp\" alt=\"Categor\u00edas al postular charlas en los eventos de comunidad\" class=\"wp-image-5024\"\/><figcaption class=\"wp-element-caption\"><strong>Categor\u00edas<\/strong> al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Vincular_una_categoria_a_la_charla\"><\/span>Vincular una categor\u00eda a la charla<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Para ser m\u00e1s efectivos con el conocimiento de nuestra comunidad ofrecemos un mecanismo donde todos los emprendedores construyamos la lista de categor\u00edas de forma que podamos usar los mismos \u00edtems o registrar nuevos \u00edtems de la siguiente forma:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/120-vincular-CATEGORIAS-edicion-charla.webp\" alt=\"Vincular categor\u00edas a la charla postulada.\" class=\"wp-image-5025\"\/><figcaption class=\"wp-element-caption\">Vincular categor\u00edas a la charla postulada.<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Creacion_de_una_nueva_categoria_al_postular_charlas_en_los_eventos_de_comunidad\"><\/span>Creaci\u00f3n de una nueva categor\u00eda al postular charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Tambi\u00e9n puedes crear una nueva categor\u00eda en caso que no encuentres la tuya en la lista preexistente:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/140-crear-CATEGORIAS-edicion-charla.webp\" alt=\"Crear categor\u00edas al postular charlas\" class=\"wp-image-5026\"\/><figcaption class=\"wp-element-caption\">Crear categor\u00edas al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Vista_de_las_categorias_en_la_landing_page_de_la_charla\"><\/span>Vista de las categor\u00edas en la landing page de la charla<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Las categor\u00edas de cada charla aparecer\u00e1n como etiquetas que la clasifican de la siguiente manera:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/150-ver-las-CATEGORIAS-edicion-charla.webp\" alt=\"Ver las categor\u00edas de la charla postulada\" class=\"wp-image-5027\"\/><figcaption class=\"wp-element-caption\">Ver las categor\u00edas de la charla postulada.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Eventos_al_postular_charlas_en_los_eventos_de_comunidad\"><\/span>Eventos al postular charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Como vimos desde el comienzo, las charlas se registrar para participar en eventos, por lo tanto debemos verificar que efectivamente nuestra charla est\u00e9 vinculada al evento (o a los eventos) donde ciertamente queremos adquirir el rol de speaker o conferencista.<\/p>\n\n\n\n<p>Es posible que registremos una charla, pero que esta no haya quedado vinculada a un evento; siguiendo con nuestro ejemplo, podemos ver que la lista de eventos de nuestra charla se encuentra vac\u00eda:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/01\/150-eventos-edicion-charla.webp\" alt=\"Eventos en los que participa la charla\" class=\"wp-image-5031\"\/><figcaption class=\"wp-element-caption\">Lista de eventos de la charla est\u00e1 vac\u00eda.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Vincular_la_charla_a_un_evento\"><\/span>Vincular la charla a un evento<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En primer lugar para poder vincular la charla a un evento, debemos estar registrados en ese evento previamente, finalmente, para vincular nuestra charla a un evento, debemos seleccionar un evento de la lista y usar el bot\u00f3n [Vincular]:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/160-mis-eventos-edicion-charla.webp\" alt=\"mis eventos al postular charlas\" class=\"wp-image-5032\"\/><figcaption class=\"wp-element-caption\">Mis eventos al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Lista_de_eventos_de_la_charla\"><\/span>Lista de eventos de la charla<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Despu\u00e9s de haber vinculado eventos a nuestra charla, la lista de eventos se ver\u00e1 de esta manera:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/170-eventos-de-la-charla-edicion-charla.webp\" alt=\"Lista de eventos al postular charlas en los eventos de comunidad\" class=\"wp-image-5033\"\/><figcaption class=\"wp-element-caption\">Lista de eventos al postular charlas en los eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Desvincular_la_charla_a_un_evento\"><\/span>Desvincular la charla a un evento<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Es posible que ya no queramos participar en un evento, por consiguiente podemos desvincular la charla usando el bot\u00f3n rojo <strong>Desvincular<\/strong>;<mark class=\"annotation-text annotation-text-yoast\" id=\"annotation-text-15a7bde1-6097-493a-b9e0-2f0186b8e445\"><\/mark> este bot\u00f3n tambi\u00e9n se encuentra en la lista de eventos al lado derecho, es importante mencionar que su uso, da como resultado la p\u00e9rdida de los votos obtenidos durante el proceso de postulaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Una_charla_postulada_en_varios_eventos_de_comunidad\"><\/span>Una charla postulada en varios eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En primer lugar debemos recordar que este servicio fue dise\u00f1ado para buscar talentos y formar nuevos conferencistas, por lo tanto, es importante resaltar que cada charla se podr\u00e1 postular en diferentes eventos con el objetivo que logre ser tenida en cuenta en un evento de comunidad y que la presentaci\u00f3n de la charla se haga realidad; claro est\u00e1 que una charla que ya haya logrado ser presentada, ya no se deber\u00e1 postular en m\u00e1s eventos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/240-Varios-eventos-landing-page-charla.webp\" alt=\"Una charla postulada en varios eventos de comunidad.\" class=\"wp-image-5063\"\/><figcaption class=\"wp-element-caption\">Una charla postulada en varios eventos de comunidad.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Obtener_la_Landing_Page_de_la_charla\"><\/span>Obtener la Landing Page de la charla<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es posible que pienses que el proceso de registro de la charla ya termin\u00f3, sin embargo es necesario revisar el contenido de nuestra charla a trav\u00e9s de la Landing Page generada.<\/p>\n\n\n\n<p>Finalmente podemos consultar la p\u00e1gina de nuestra charla de varias maneras:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A trav\u00e9s de la URL corta o Slug que suministramos.<\/li>\n\n\n\n<li>A partir del bot\u00f3n verde <strong>Vista previa<\/strong>, que aparece en la p\u00e1gina de edici\u00f3n de la charla.<\/li>\n\n\n\n<li>En el men\u00fa <strong>Eventos<\/strong> en la opci\u00f3n <strong>Mis Charlas.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Para este ejemplo usamos la siguiente URL: <a href=\"https:\/\/p4s.co\/el-riesgo-de-las-energias-limpias\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\">https:\/\/p4s.co\/el-riesgo-de-las-energias-limpias<\/a> , Aun as\u00ed, recordemos que podemos cambiar la URL por una que sea amigable y se acople a nuestra necesidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Compartir_tu_charla_para_recibir_votos\"><\/span>Compartir tu charla para recibir votos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Antes de empezar a solicitar votos es importante que hagas un listado de los medios que usar\u00e1s para solicitar votos, de igual forma tambi\u00e9n es crucial revisar la visualizaci\u00f3n de tus publicaciones en dichos medios. A continuaci\u00f3n te presentar\u00e9 las herramientas m\u00e1s usadas para este prop\u00f3sito y adem\u00e1s incluir\u00e9 algunos tips para su correcto uso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Facebook_Debugger_al_postular_charlas_en_los_eventos_de_comunidad\"><\/span>Facebook Debugger al postular charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Facebook es uno de los medios de difusi\u00f3n m\u00e1s usados, por lo tanto cuenta con una muy buena herramienta que adem\u00e1s de mostrar la previsualizaci\u00f3n de las publicaciones, nos ofrece informaci\u00f3n t\u00e9cnica acerca de nuestro sitio web, para usarla debes ingresar a: <a href=\"https:\/\/developers.facebook.com\/tools\/debug\/\">https:\/\/developers.facebook.com\/tools\/debug\/<\/a> <\/p>\n\n\n\n<p>Cabe resaltar que Facebook publica la imagen con una relaci\u00f3n de aspecto 16:9, por esta raz\u00f3n debemos poner el texto de manera estrat\u00e9gica para que sea visible de esta forma:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/190-facebook-landing-page-charla.webp\" alt=\"Landing page en Facebook\" class=\"wp-image-5039\" style=\"width:483px;height:398px\"\/><figcaption class=\"wp-element-caption\">Landing page en Facebook<\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Twitter_Card_para_postular_charlas_en_los_eventos_de_comunidad\"><\/span>Twitter Card para postular charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>De manera similar a Facebook, Twitter sigue siendo un buen lugar para distribuir contenido y adem\u00e1s tambi\u00e9n cuenta con una gran herramienta para previsualizar los tweets antes de enviarlos, para usarla debemos ingresar a: <a href=\"https:\/\/cards-dev.twitter.com\/validator\">https:\/\/cards-dev.twitter.com\/validator<\/a>  <\/p>\n\n\n\n<p>A diferencia de las herramientas anteriores, en esta podemos ver que la imagen es cuadrada (1:1), por lo tanto nuestro texto al interior del banner debe estar centrado de manera que sea completamente legible.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/200-twitter-landing-page-charla.webp\" alt=\"Landing page en Twitter\" class=\"wp-image-5040\" style=\"width:550px;height:391px\"\/><figcaption class=\"wp-element-caption\">Landing page en Twitter<\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"LinkedIn\"><\/span>LinkedIn<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Probablemente quieras presentar tu charla en un ambiente m\u00e1s corporativo, por esta raz\u00f3n es posible que quieras buscar votos en LinkedIn, mediante su herramienta llamada Post Inspector, para usarla deber ir a <a rel=\"noreferrer noopener\" aria-label=\"https:\/\/www.linkedin.com\/post-inspector\/  (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.linkedin.com\/post-inspector\/\" target=\"_blank\">https:\/\/www.linkedin.com\/post-inspector\/ <\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/210-linkedin-landing-page-charla.webp\" alt=\"Landing page en LinkedIn\" class=\"wp-image-5043\" style=\"width:471px;height:350px\"\/><figcaption class=\"wp-element-caption\">Landing page en LinkedIn.<\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"WhatsApp\"><\/span>WhatsApp<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Una de las manera m\u00e1s r\u00e1pidas para presentar contenidos a personas de c\u00edrculos sociales cercanos es WhatsApp, sobre todo en los grupos y las listas de difusi\u00f3n.<\/p>\n\n\n\n<p>Antes de enviar la URL de la charla, es recomendable probarlo con un n\u00famero de confianza para validar su correcto funcionamiento, Debido a que WhatsApp tiene dos comportamientos diferentes al momento de compartir a trav\u00e9s del m\u00f3vil y de un pc mediante el WhatsApp Web.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/220-WhatsApp-web-landing-page-charla.webp\" alt=\"Landing page publicada a trav\u00e9s de WhatsApp web\" class=\"wp-image-5044\"\/><figcaption class=\"wp-element-caption\">Landing page publicada a trav\u00e9s de WhatsApp web<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/230-WhatsApp-Movil-landing-page-charla.webp\" alt=\"Landing page publicada a trav\u00e9s de WhatsApp directamente en el m\u00f3vil\" class=\"wp-image-5045\"\/><figcaption class=\"wp-element-caption\">Landing page publicada a trav\u00e9s de WhatsApp directamente en el m\u00f3vil<\/figcaption><\/figure>\n\n\n\n<p>Personalmente me parece que el post es m\u00e1s impactante cuando se publica directamente desde el dispositivo m\u00f3vil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Compartir_desde_la_Landing_Page_de_las_charlas_en_los_eventos_de_comunidad\"><\/span>Compartir desde la Landing Page de las charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Para nosotros es de gran importancia la difusi\u00f3n de los contenidos registrados en nuestra plataforma digital, por esta raz\u00f3n cada Landing Page de p4s.co ofrece los mecanismos necesarios para compartir el contenido en diferentes canales, sobre todo, canales de social media. Tanto en la versi\u00f3n escritorio, como en la versi\u00f3n movil, los usuarios encontrar\u00e1n en cada Landing Page la siguiente barra de herramientas:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/250-compartir-movil-landing-page-charla.webp\" alt=\"Compartir la Landing Page en versi\u00f3n m\u00f3vil.\" class=\"wp-image-5066\"\/><figcaption class=\"wp-element-caption\">Compartir la Landing Page en versi\u00f3n m\u00f3vil.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/260-compartir-desktop-landing-page-charla.webp\" alt=\"Compartir la Landing Page en versi\u00f3n desktop\" class=\"wp-image-5065\"\/><figcaption class=\"wp-element-caption\">Compartir la Landing Page en versi\u00f3n desktop.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Votaciones_al_postular_charlas_en_los_eventos_de_comunidad\"><\/span>Votaciones al postular charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es posible que sepas c\u00f3mo se escog\u00edan a los conferencistas en el pasado, sin embargo, desde ahora los conferencistas se escoger\u00e1n a partir de las votaciones. Cada evento de comunidad cuenta con una etapa de votaciones, por esta raz\u00f3n s\u00f3lo se recibir\u00e1n votos en estas fechas.<\/p>\n\n\n\n<p>Finalmente, nuestro sistema de votos funciona tanto en la Landing Page de cada charla, como en las p\u00e1ginas de los eventos de comunidad, donde adem\u00e1s de presentar los detalles de un evento, tambi\u00e9n aparece el listado de todas las charlas postuladas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Votar_en_la_Landing_Page_de_una_charla\"><\/span>Votar en la Landing Page de una charla<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Como resultado del registro de una charla en nuestra plataforma, el usuario recibe una Landing Page en la que adem\u00e1s poder consultar los detalles b\u00e1sicos, aparece una opci\u00f3n para recibir la votaci\u00f3n de la siguiente manera:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/270-votar-desde-landing-page-charla.webp\" alt=\"Votar por una charla en un evento desde la Landing Page.\" class=\"wp-image-5070\"\/><figcaption class=\"wp-element-caption\">Votar por una charla en un evento desde la Landing Page.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Votar_por_charlas_en_los_eventos_de_comunidad\"><\/span>Votar por charlas en los eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Probablemente ya conozcas cual es el aspecto de una p\u00e1gina de evento de comunidad, sin embargo debes saber que puedes votar y tambi\u00e9n recibir votos directamente en la p\u00e1gina del evento de la siguiente forma:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/280-votar-desde-landing-page-del-evento.webp\" alt=\"Votar por varias charlas desde la p\u00e1gina del evento\" class=\"wp-image-5071\"\/><figcaption class=\"wp-element-caption\">Votar por varias charlas desde la p\u00e1gina del evento.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pedir_votos_al_publico_externo_a_p4sco\"><\/span>Pedir votos al p\u00fablico externo a p4s.co<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Seguramente la mayor\u00eda de votos van a provenir de los miembros de nuestra red, no obstante, hemos dise\u00f1ado un mecanismo que seguramente facilitar\u00e1 a los conferencistas solicitar votos a sus amigos, familiares, compa\u00f1eros de trabajo, etc. que todav\u00eda no hagan parte de nuestro ecosistema digital, por esta raz\u00f3n, un usuario externo que desee votar ver\u00e1 el siguiente formato:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/290-votar-usuario-externo-a-p4s.webp\" alt=\"Formato de voto para personas externas a p4s.co\" class=\"wp-image-5074\"\/><figcaption class=\"wp-element-caption\">Formato de voto para personas externas a p4s.co<\/figcaption><\/figure>\n\n\n\n<p>Como podr\u00e1s ver, el sistema solicitar\u00e1 el nombre completo, un e-mail y la resoluci\u00f3n de una operaci\u00f3n matem\u00e1tica realizada por una persona.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/300-notificacion-de-voto-externo-a-p4s.webp\" alt=\"El interesado en votar recibe notificaci\u00f3n del proceso\" class=\"wp-image-5075\" style=\"width:309px;height:138px\"\/><figcaption class=\"wp-element-caption\">El interesado en votar recibe notificaci\u00f3n del proceso.<\/figcaption><\/figure><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"E-mail_de_confirmacion_al_votar_por_charlas_en_eventos_de_comunidad\"><\/span>E-mail de confirmaci\u00f3n al votar por charlas en eventos de comunidad<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Despu\u00e9s de recibir estos datos, nuestro sistema enviar\u00e1 inmediatamente un e-mail con instrucciones para validar el voto.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/310-notificacion-email-de-voto-externo-a-p4s.webp\" alt=\"Llegar\u00e1 un e-mail invitando a confirmar el voto por la charla postulada en el evento de comunidad.\" class=\"wp-image-5076\"\/><figcaption class=\"wp-element-caption\">Llegar\u00e1 un e-mail invitando a confirmar el voto.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/320-email-de-voto-externo-a-p4s.webp\" alt=\"E-mail con instrucciones para confirmar el voto por la charla postulada en el evento de comunidad\" class=\"wp-image-5077\"\/><figcaption class=\"wp-element-caption\">E-mail con instrucciones para confirmar el voto por la charla postulada.<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Voto_confirmado\"><\/span>Voto confirmado<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Finalmente al recibir la confirmaci\u00f3n del voto, el sistema presentar\u00e1 la siguiente ventana informando que el voto ha sido recibido y tambi\u00e9n aprovechamos esta oportunidad para invitar al votante a asistir al evento ya que probablemente el tema sea de su inter\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/330-confirmacion-voto-externo-a-p4s.webp\" alt=\"Confirmaci\u00f3n de voto externo recibido e invitaci\u00f3n al evento de comunidad\" class=\"wp-image-5078\"\/><figcaption class=\"wp-element-caption\">Confirmaci\u00f3n de voto externo recibido e invitaci\u00f3n al evento de comunidad.<\/figcaption><\/figure>\n\n\n\n<p>Por \u00faltimo, si el usuario decide solicitar la invitaci\u00f3n, nuestra plataforma digital le enviar\u00e1 un e-mail con los detalles del evento y tambi\u00e9n con cita en la agenda<mark class=\"annotation-text annotation-text-yoast\" id=\"annotation-text-5d46e552-35ed-4b8d-9caa-3fe80abe5b02\"><\/mark> de la siguiente manera:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/p4s.co\/news\/wp-content\/\/uploads\/2022\/02\/340-invitacion-voto-externo-a-p4s.webp\" alt=\"\" class=\"wp-image-5079\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Contenidos_todas_las_semanas\"><\/span>Contenidos todas las semanas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"has-medium-font-size\">Suscr\u00edbete a nuestro canal de <a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.youtube.com\/c\/p4slive\/\" target=\"_blank\">YouTube<\/a> y sigue nuestra p\u00e1gina en <a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/facebook.com\/p4s.co\/\" target=\"_blank\">Facebook:<\/a><\/p>\n\n\n\n<p><strong>Link de FaceBook: <\/strong><a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.facebook.com\/p4sco\/\" target=\"_blank\"><strong>https:\/\/www.facebook.com\/p4sco\/<\/strong><\/a> <\/p>\n\n\n\n<p><strong>Link YouTube : <\/strong><a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.youtube.com\/c\/p4slive\" target=\"_blank\"><strong>https:\/\/www.youtube.com\/c\/p4slive  <\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convi\u00e9rtete en el protagonista al postular charlas en los eventos de comunidad y g\u00e1nate tu lugar como conferencista a trav\u00e9s de las votaciones del p\u00fablico. Tambi\u00e9n recibir\u00e1s apoyo para que mejores tu marca personal y aprender\u00e1s t\u00e9cnicas para crear y fortalecer tu propia audiencia.<\/p>\n","protected":false},"author":7,"featured_media":4847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,490,31],"tags":[484,17,481,11,483,258,482,104],"class_list":["post-4846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-ayuda","category-edutech","tag-conferencistas","tag-emprendimiento","tag-eventos-comunidad","tag-p4s","tag-ponente","tag-servicios","tag-speakers","tag-tecnologia"],"_links":{"self":[{"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/posts\/4846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/comments?post=4846"}],"version-history":[{"count":83,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/posts\/4846\/revisions"}],"predecessor-version":[{"id":9165,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/posts\/4846\/revisions\/9165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/media\/4847"}],"wp:attachment":[{"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/media?parent=4846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/categories?post=4846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/p4s.co\/news\/wp-json\/wp\/v2\/tags?post=4846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}